{"id":69,"count":0,"description":"","link":"https:\/\/sujoya.es\/en\/product-category\/joyas-de-plata\/cadenas-plata\/","name":"Chains","slug":"cadenas-plata","taxonomy":"product_cat","parent":29,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cadenas archivos - Joyeria Sujoya<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sujoya.es\/en\/product-category\/joyas-de-plata\/cadenas-plata\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cadenas archivos - Joyeria Sujoya\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sujoya.es\/en\/product-category\/joyas-de-plata\/cadenas-plata\/\" \/>\n<meta property=\"og:site_name\" content=\"Joyeria Sujoya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/sujoya.es\/categoria-producto\/joyas-de-plata\/cadenas-plata\/\",\"url\":\"https:\/\/sujoya.es\/categoria-producto\/joyas-de-plata\/cadenas-plata\/\",\"name\":\"Cadenas archivos - Joyeria Sujoya\",\"isPartOf\":{\"@id\":\"https:\/\/sujoya.es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/sujoya.es\/categoria-producto\/joyas-de-plata\/cadenas-plata\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sujoya.es\/categoria-producto\/joyas-de-plata\/cadenas-plata\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/sujoya.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joyas de plata\",\"item\":\"https:\/\/sujoya.es\/categoria-producto\/joyas-de-plata\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cadenas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sujoya.es\/#website\",\"url\":\"https:\/\/sujoya.es\/\",\"name\":\"Joyeria Su Joya\",\"description\":\"\u00a1Joyer\u00eda Sujoya en Valladolid desde hace m\u00e1s de 20 a\u00f1os! \ud83d\udc8d\u2728 Descubre nuestras colecciones de relojes, joyas, alianzas... #Joyer\u00edaValladolid\",\"publisher\":{\"@id\":\"https:\/\/sujoya.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sujoya.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sujoya.es\/#organization\",\"name\":\"Joyeria Su Joya\",\"url\":\"https:\/\/sujoya.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/sujoya.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sujoya.es\/wp-content\/uploads\/2023\/11\/logotipo_web.png\",\"contentUrl\":\"https:\/\/sujoya.es\/wp-content\/uploads\/2023\/11\/logotipo_web.png\",\"width\":1185,\"height\":339,\"caption\":\"Joyeria Su Joya\"},\"image\":{\"@id\":\"https:\/\/sujoya.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cadenas archivos - Joyeria Sujoya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sujoya.es\/en\/product-category\/joyas-de-plata\/cadenas-plata\/","og_locale":"en_GB","og_type":"article","og_title":"Cadenas archivos - Joyeria Sujoya","og_url":"https:\/\/sujoya.es\/en\/product-category\/joyas-de-plata\/cadenas-plata\/","og_site_name":"Joyeria Sujoya","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sujoya.es\/categoria-producto\/joyas-de-plata\/cadenas-plata\/","url":"https:\/\/sujoya.es\/categoria-producto\/joyas-de-plata\/cadenas-plata\/","name":"Cadenas archivos - Joyeria Sujoya","isPartOf":{"@id":"https:\/\/sujoya.es\/#website"},"breadcrumb":{"@id":"https:\/\/sujoya.es\/categoria-producto\/joyas-de-plata\/cadenas-plata\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/sujoya.es\/categoria-producto\/joyas-de-plata\/cadenas-plata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sujoya.es\/"},{"@type":"ListItem","position":2,"name":"Joyas de plata","item":"https:\/\/sujoya.es\/categoria-producto\/joyas-de-plata\/"},{"@type":"ListItem","position":3,"name":"Cadenas"}]},{"@type":"WebSite","@id":"https:\/\/sujoya.es\/#website","url":"https:\/\/sujoya.es\/","name":"Joyeria Su Joya","description":"Sujoya Jewelry in Valladolid for over 20 years! \ud83d\udc8d\u2728 Discover our collections of watches, jewelry, wedding rings... #Joyer\u00edaValladolid","publisher":{"@id":"https:\/\/sujoya.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sujoya.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/sujoya.es\/#organization","name":"Joyeria Su Joya","url":"https:\/\/sujoya.es\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/sujoya.es\/#\/schema\/logo\/image\/","url":"https:\/\/sujoya.es\/wp-content\/uploads\/2023\/11\/logotipo_web.png","contentUrl":"https:\/\/sujoya.es\/wp-content\/uploads\/2023\/11\/logotipo_web.png","width":1185,"height":339,"caption":"Joyeria Su Joya"},"image":{"@id":"https:\/\/sujoya.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sujoya.es\/en\/wp-json\/wp\/v2\/product_cat\/69","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sujoya.es\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/sujoya.es\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/sujoya.es\/en\/wp-json\/wp\/v2\/product_cat\/29"}],"wp:post_type":[{"href":"https:\/\/sujoya.es\/en\/wp-json\/wp\/v2\/product?product_cat=69"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}